{"id":13391,"date":"2023-01-25T22:57:58","date_gmt":"2023-01-25T20:57:58","guid":{"rendered":"https:\/\/al-rawiya.com\/%d8%a7%d9%83%d8%aa%d8%a8-%d9%85%d8%b9%d9%86%d8%a7\/"},"modified":"2024-07-03T15:34:34","modified_gmt":"2024-07-03T12:34:34","slug":"%d8%a7%d9%83%d8%aa%d8%a8%d9%88%d8%a7-%d9%85%d8%b9%d9%86%d8%a7","status":"publish","type":"page","link":"https:\/\/al-rawiya.com\/ar\/%d8%a7%d9%83%d8%aa%d8%a8%d9%88%d8%a7-%d9%85%d8%b9%d9%86%d8%a7\/","title":{"rendered":"\u0627\u0643\u062a\u0628\u0648\u0627 \u0645\u0639\u0646\u0627"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13391\" class=\"elementor elementor-13391 elementor-7849\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d39f96 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3d39f96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e620f6d\" data-id=\"e620f6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d3efdf elementor-widget elementor-widget-image\" data-id=\"3d3efdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"4993\" height=\"3333\" src=\"https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?fit=4993%2C3333&amp;ssl=1\" class=\"attachment-full size-full wp-image-8068\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?w=4993&amp;ssl=1 4993w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?resize=1536%2C1025&amp;ssl=1 1536w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?resize=2048%2C1367&amp;ssl=1 2048w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?resize=1200%2C801&amp;ssl=1 1200w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/al-rawiya.com\/wp-content\/uploads\/2023\/01\/Write-With-Us-Photo-by-Brent-Gorwin-on-Unsplash.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0acfd05 elementor-widget elementor-widget-heading\" data-id=\"0acfd05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0627\u0643\u062a\u0628\u0648\u0627 \u0645\u0639\u0646\u0627<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a8ba8dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8ba8dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ddcd62c\" data-id=\"ddcd62c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bdfc233\" data-id=\"bdfc233\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a35f22 elementor-widget elementor-widget-text-editor\" data-id=\"4a35f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0634\u0643\u0631\u064b\u0627 \u0644\u0627\u062e\u062a\u064a\u0627\u0631\u0643\u0645 &#8220;\u0627\u0644\u0631\u0627\u0648\u064a\u0629&#8221; \u0644\u0646\u0634\u0631 \u0623\u0639\u0645\u0627\u0644\u0643\u0645. \u0642\u0628\u0644 \u062a\u0642\u062f\u064a\u0645 \u0645\u0642\u062a\u0631\u062d\u060c \u064a\u064f\u0631\u062c\u0649 \u062a\u0635\u0641\u062d \u0645\u0648\u0642\u0639\u0646\u0627 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a. \u0646\u0648\u0635\u064a \u0628\u0642\u0631\u0627\u0621\u0629 \u0635\u0641\u062d\u0629 &#8220;\u0645\u0646 \u0646\u062d\u0646&#8221; \u0648\u0627\u0644\u0625\u0635\u062f\u0627\u0631\u0627\u062a \u0627\u0644\u0633\u0627\u0628\u0642\u0629 \u062d\u062a\u0649 \u062a\u062a\u0639\u0631\u0641\u0648\u0627 \u0639\u0644\u0649 \u0623\u0633\u0644\u0648\u0628\u0646\u0627 \u0648\u0645\u0647\u0645\u062a\u0646\u0627 \u0648\u0645\u0627 \u0646\u0634\u0631\u0646\u0627\u0647 \u0633\u0627\u0628\u0642\u064b\u0627. \u0633\u064a\u0633\u0627\u0639\u062f\u0643\u0645 \u0630\u0644\u0643 \u0639\u0644\u0649 \u062a\u062d\u0633\u064a\u0646 \u062a\u0642\u062f\u064a\u0645\u0643\u0645 \u0648\u064a\u0639\u0632\u0632 \u0645\u0646 \u0641\u0631\u0635 \u062a\u0639\u0627\u0648\u0646\u0646\u0627 \u0627\u0644\u0645\u0633\u062a\u0642\u0628\u0644\u064a.<\/p><p>\u00a0<\/p><p>\u0642\u062f \u064a\u0643\u0648\u0646 \u0642\u0631\u0627\u0621 \u0648\u0645\u0633\u0627\u0647\u0645\u0648 \u0648\u0641\u0631\u064a\u0642 \u0639\u0645\u0644 &#8220;\u0627\u0644\u0631\u0627\u0648\u064a\u0629&#8221; \u0645\u0642\u064a\u0645\u064a\u0646 \u0641\u064a \u0623\u064a \u0645\u0643\u0627\u0646 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u0644\u0643\u0646\u0647\u0645 \u064a\u0634\u0639\u0631\u0648\u0646 \u062f\u0627\u0626\u0645\u064b\u0627 \u0628\u0627\u0644\u0627\u0631\u062a\u0628\u0627\u0637 \u0648\u0627\u0644\u062d\u0628 \u0644\u0628\u0644\u062f\u0627\u0646 \u0628\u0644\u0627\u062f \u0627\u0644\u0634\u0627\u0645. \u0646\u0633\u0639\u0649 \u0644\u062a\u0639\u0632\u064a\u0632 \u0631\u0648\u0627\u0628\u0637\u0646\u0627 \u0645\u0639 \u0645\u0646\u0637\u0642\u062a\u0646\u0627 \u0648\u0645\u062c\u062a\u0645\u0639\u0627\u062a\u0647\u0627 \u0627\u0644\u0645\u062a\u0646\u0648\u0639\u0629 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0633\u0631\u062f \u0642\u0635\u0635\u0647\u0627\u060c \u062e\u0635\u0648\u0635\u064b\u0627 \u062a\u0644\u0643 \u0627\u0644\u0642\u0635\u0635 \u063a\u064a\u0631 \u0627\u0644\u0645\u0639\u0631\u0648\u0641\u0629 \u0648\u063a\u064a\u0631 \u0627\u0644\u0645\u0631\u0648\u064a\u0629\u060c \u0633\u0648\u0627\u0621 \u0643\u0627\u0646\u062a \u0639\u0646 \u0627\u0644\u0645\u0627\u0636\u064a \u0623\u0648 \u0627\u0644\u062d\u0627\u0636\u0631 \u0623\u0648 \u0627\u0644\u0645\u0633\u062a\u0642\u0628\u0644 \u0627\u0644\u0630\u064a \u0646\u062a\u0645\u0646\u0649 \u0623\u0646 \u0646\u0631\u0627\u0647.<\/p><p>\u00a0<\/p><p><strong>\u0646\u0631\u062d\u0628 \u0628\u0623\u0634\u0643\u0627\u0644 \u062c\u062f\u064a\u062f\u0629 \u0645\u0646 \u0627\u0644\u0643\u062a\u0627\u0628\u0627\u062a\u060c \u0648\u0644\u0643\u0646\u0646\u0627 \u062d\u0627\u0644\u064a\u0627\u064b \u0646\u0646\u0634\u0631:<\/strong><\/p><p>&#8211; \u0645\u0642\u0627\u0644\u0627\u062a \u0645\u0643\u062a\u0648\u0628\u0629 \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0645\u0642\u0627\u0644\u0627\u062a \u0627\u0644\u0631\u0623\u064a\u060c \u0627\u0644\u062d\u062c\u062c\u060c \u0645\u0631\u0627\u062c\u0639\u0627\u062a \u0627\u0644\u0623\u0641\u0644\u0627\u0645\u060c \u0627\u0644\u062a\u0644\u0641\u0632\u064a\u0648\u0646\u060c \u0627\u0644\u0645\u0648\u0633\u064a\u0642\u0649\u060c \u0623\u0648 \u0627\u0644\u0641\u0646\u060c \u0627\u0644\u062a\u062d\u0644\u064a\u0644\u060c \u0627\u0644\u0623\u062f\u0644\u0629\u060c \u0648\u0627\u0644\u0634\u0631\u0648\u062d\u0627\u062a.<\/p><p>&#8211; \u0645\u0642\u0627\u0628\u0644\u0627\u062a<\/p><p>&#8211; \u062a\u0635\u0648\u064a\u0631 \u0641\u0648\u062a\u0648\u063a\u0631\u0627\u0641\u064a \u0648\u0645\u0642\u0627\u0644\u0627\u062a \u0645\u0635\u0648\u0631\u0629<\/p><p>&#8211; \u0631\u0633\u0648\u0645\u0627\u062a \u0648\u0623\u0639\u0645\u0627\u0644 \u0641\u0646\u064a\u0629 \u0623\u062e\u0631\u0649<\/p><p>&#8211; \u0634\u0639\u0631<\/p><p>&#8211; \u0641\u064a\u062f\u064a\u0648\u0647\u0627\u062a<\/p><p>\u00a0<\/p><p><strong>\u064a\u0631\u062c\u0649 \u0639\u062f\u0645 \u062a\u0642\u062f\u064a\u0645:<\/strong><\/p><p>&#8211; \u0623\u0639\u0645\u0627\u0644 \u0645\u0646\u0634\u0648\u0631\u0629 \u0633\u0627\u0628\u0642\u064b\u0627<\/p><p>&#8211; \u0623\u0639\u0645\u0627\u0644 \u062a\u0631\u0648\u0651\u062c \u0644\u0644\u0639\u0646\u0635\u0631\u064a\u0629 \u0623\u0648 \u0627\u0644\u062a\u0645\u064a\u064a\u0632 \u0627\u0644\u062c\u0646\u0633\u064a \u0623\u0648 \u0631\u0647\u0627\u0628 \u0627\u0644\u0645\u062b\u0644\u064a\u064a\u0646 \u0623\u0648 \u0631\u0647\u0627\u0628 \u0627\u0644\u0645\u062a\u062d\u0648\u0644\u064a\u0646 \u062c\u0646\u0633\u064a\u064b\u0627 \u0623\u0648 \u0627\u0644\u0637\u0627\u0626\u0641\u064a\u0629<\/p><p>&#8211; \u0645\u0642\u0627\u0644\u0627\u062a \u063a\u064a\u0631 \u0630\u0627\u062a \u0635\u0644\u0629 \u0628\u0644\u0628\u0646\u0627\u0646\u060c \u0633\u0648\u0631\u064a\u0627\u060c \u0641\u0644\u0633\u0637\u064a\u0646\u060c \u0623\u0648 \u0627\u0644\u0623\u0631\u062f\u0646<\/p><p>\u00a0<\/p><p>\u062d\u0627\u0644\u064a\u064b\u0627\u060c \u0646\u0646\u0634\u0631 \u0628\u0627\u0644\u0644\u063a\u062a\u064a\u0646 \u0627\u0644\u0625\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0648\u0627\u0644\u0639\u0631\u0628\u064a\u0629\u060c \u0644\u0630\u0627 \u0644\u0627 \u062a\u062a\u0631\u062f\u062f\u0648\u0627 \u0641\u064a \u0625\u0631\u0633\u0627\u0644 \u0645\u0642\u062a\u0631\u062d\u0627\u062a\u0643\u0645 \u0628\u0623\u064a \u0645\u0646 \u0627\u0644\u0644\u063a\u062a\u064a\u0646.<\/p><p>\u00a0<\/p><p>\u0623\u062e\u064a\u0631\u064b\u0627\u060c \u0646\u0637\u0644\u0628 \u0645\u0646 \u0627\u0644\u0645\u0633\u0627\u0647\u0645\u064a\u0646 \u0627\u0644\u0645\u062d\u062a\u0645\u0644\u064a\u0646 \u062a\u0642\u062f\u064a\u0645 \u0645\u0642\u062a\u0631\u062d\/\u0645\u0644\u062e\u0635 (\u0648\u0644\u064a\u0633 \u0645\u0633\u0648\u062f\u0629 \u0646\u0647\u0627\u0626\u064a\u0629) \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u064a\u0646\u0629 \u0643\u062a\u0627\u0628\u0629 \u0648\u0627\u062d\u062f\u0629 \u0639\u0644\u0649 \u0627\u0644\u0623\u0642\u0644 \u0644\u0644\u0645\u0642\u0627\u0644\u0627\u062a \u0627\u0644\u0645\u0643\u062a\u0648\u0628\u0629 \u0648\u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0627\u062a. \u0625\u0630\u0627 \u0643\u0627\u0646 \u0644\u062f\u064a\u0643\u0645 \u0623\u064a \u0623\u0633\u0626\u0644\u0629 \u062d\u0648\u0644 \u0645\u0646\u0634\u0648\u0631\u0627\u062a\u0646\u0627 \u0623\u0648 \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u062a\u0642\u062f\u064a\u0645 \u0623\u0648 \u0645\u0627 \u0646\u0628\u062d\u062b \u0639\u0646\u0647 \u062a\u062d\u062f\u064a\u062f\u064b\u0627\u060c \u0641\u0644\u0627 \u062a\u062a\u0631\u062f\u062f\u0648\u0627 \u0641\u064a \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627 \u0639\u0628\u0631 \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a info@al-rawiya.com.<\/p><p>\u00a0<\/p><p>\u0646\u062a\u0637\u0644\u0639 \u0644\u0633\u0645\u0627\u0639 \u0623\u062e\u0628\u0627\u0631\u0643\u0645 \u0648\u0642\u0631\u0627\u0621\u0629 \u0623\u0639\u0645\u0627\u0644\u0643\u0645 \u0628\u0639\u0646\u0627\u064a\u0629!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6afc8d elementor-widget elementor-widget-text-editor\" data-id=\"d6afc8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0644\u0627 \u0646\u0633\u062a\u0642\u0628\u0644 \u0623\u064a \u0645\u0642\u062a\u0631\u062d\u0627\u062a \u062d\u0627\u0644\u064a\u064b\u0627. \u064a\u064f\u0631\u062c\u0649 \u0645\u062a\u0627\u0628\u0639\u0629 \u0625\u0639\u0644\u0627\u0646\u0627\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0645\u0648\u0636\u0648\u0639 \u0627\u0644\u0639\u062f\u062f \u0627\u0644\u0642\u0627\u062f\u0645 \u0648 \u062a\u0627\u0631\u064a\u062e \u0641\u062a\u062d \u0628\u0627\u0628 \u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0627\u062a.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-807934e\" data-id=\"807934e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-266d839 elementor-widget elementor-widget-shortcode\" data-id=\"266d839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"forminator-ui forminator-custom-form forminator-custom-form-8446 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-8446\" data-uid=\"6a97ea6fc864d\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-8446\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-8446 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"8446\"\n\t\t\t\tenctype=\"multipart\/form-data\" data-color-option=\"default\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a97ea6fc864d\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-12 \"><div class=\"forminator-row forminator-no-margin\" data-multiple=\"true\"><div class=\"forminator-col forminator-col-md-6\"><div class=\"forminator-field\"><input type=\"text\" name=\"name-1-first-name\" placeholder=\"First Name\" id=\"forminator-field-first-name-1_6a97ea6fc864d\" class=\"forminator-input\" aria-required=\"true\" data-multi=\"1\" autocomplete=\"given-name\" value=\"\" \/><\/div><\/div><div class=\"forminator-col forminator-col-md-6\"><div class=\"forminator-field\"><input type=\"text\" name=\"name-1-last-name\" placeholder=\"Last Name\" id=\"forminator-field-last-name-1_6a97ea6fc864d\" class=\"forminator-input\" aria-required=\"true\" data-multi=\"1\" autocomplete=\"family-name\" value=\"\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12 \"><div class=\"forminator-field\"><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"Email address\" id=\"forminator-field-email-1_6a97ea6fc864d\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"address-1\" class=\"forminator-field-address forminator-col forminator-col-12 \"><div class=\"forminator-row\" data-multiple=\"false\"><div id=\"address-1-city\" class=\"forminator-col forminator-col-12\"><div class=\"forminator-field\"><input type=\"text\" name=\"address-1-city\" placeholder=\"City\" id=\"forminator-field-address-1-city_6a97ea6fc864d\" class=\"forminator-input\" data-required=\"1\" aria-required=\"true\" autocomplete=\"address-level2\" value=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\" data-multiple=\"false\"><div id=\"address-1-country\" class=\"forminator-col forminator-col-12\"><div class=\"forminator-field\"><select name=\"address-1-country\" id=\"forminator-field-8446__field--address-1-country_6a97ea6fc864d\" class=\"forminator-select2\" data-search=\"true\" data-placeholder=\"Select country\" autocomplete=\"country-name\" data-default-value=\"Lebanon\"><option value=\"\" data-country-code=\"\" selected=\"selected\"><\/option><option value=\"Afghanistan\" data-country-code=\"AF\" >Afghanistan<\/option><option value=\"Albania\" data-country-code=\"AL\" >Albania<\/option><option value=\"Algeria\" data-country-code=\"DZ\" >Algeria<\/option><option value=\"American Samoa\" data-country-code=\"AS\" >American Samoa<\/option><option value=\"Andorra\" data-country-code=\"AD\" >Andorra<\/option><option value=\"Angola\" data-country-code=\"AO\" >Angola<\/option><option value=\"Anguilla\" data-country-code=\"AI\" >Anguilla<\/option><option value=\"Antarctica\" data-country-code=\"AQ\" >Antarctica<\/option><option value=\"Antigua &amp; Barbuda\" data-country-code=\"AG\" >Antigua &amp; Barbuda<\/option><option value=\"Argentina\" data-country-code=\"AR\" >Argentina<\/option><option value=\"Armenia\" data-country-code=\"AM\" >Armenia<\/option><option value=\"Aruba\" data-country-code=\"AW\" >Aruba<\/option><option value=\"Ascension Island\" data-country-code=\"AC\" >Ascension Island<\/option><option value=\"Australia\" data-country-code=\"AU\" >Australia<\/option><option value=\"Austria\" data-country-code=\"AT\" >Austria<\/option><option value=\"Azerbaijan\" data-country-code=\"AZ\" >Azerbaijan<\/option><option value=\"Bahamas\" data-country-code=\"BS\" >Bahamas<\/option><option value=\"Bahrain\" data-country-code=\"BH\" >Bahrain<\/option><option value=\"Bangladesh\" data-country-code=\"BD\" >Bangladesh<\/option><option value=\"Barbados\" data-country-code=\"BB\" >Barbados<\/option><option value=\"Belarus\" data-country-code=\"BY\" >Belarus<\/option><option value=\"Belgium\" data-country-code=\"BE\" >Belgium<\/option><option value=\"Belize\" data-country-code=\"BZ\" >Belize<\/option><option value=\"Benin\" data-country-code=\"BJ\" >Benin<\/option><option value=\"Bermuda\" data-country-code=\"BM\" >Bermuda<\/option><option value=\"Bhutan\" data-country-code=\"BT\" >Bhutan<\/option><option value=\"Bolivia\" data-country-code=\"BO\" >Bolivia<\/option><option value=\"Bosnia and Herzegovina\" data-country-code=\"BA\" >Bosnia and Herzegovina<\/option><option value=\"Botswana\" data-country-code=\"BW\" >Botswana<\/option><option value=\"Bouvet Island\" data-country-code=\"BV\" >Bouvet Island<\/option><option value=\"Brazil\" data-country-code=\"BR\" >Brazil<\/option><option value=\"British Indian Ocean Territory\" data-country-code=\"IO\" >British Indian Ocean Territory<\/option><option value=\"British Virgin Islands\" data-country-code=\"VG\" >British Virgin Islands<\/option><option value=\"Brunei\" data-country-code=\"BN\" >Brunei<\/option><option value=\"Bulgaria\" data-country-code=\"BG\" >Bulgaria<\/option><option value=\"Burkina Faso\" data-country-code=\"BF\" >Burkina Faso<\/option><option value=\"Burundi\" data-country-code=\"BI\" >Burundi<\/option><option value=\"Cabo Verde\" data-country-code=\"CV\" >Cabo Verde<\/option><option value=\"Cambodia\" data-country-code=\"KH\" >Cambodia<\/option><option value=\"Cameroon\" data-country-code=\"CM\" >Cameroon<\/option><option value=\"Canada\" data-country-code=\"CA\" >Canada<\/option><option value=\"Caribbean Netherlands\" data-country-code=\"BQ\" >Caribbean Netherlands<\/option><option value=\"Cayman Islands\" data-country-code=\"KY\" >Cayman Islands<\/option><option value=\"Central African Republic\" data-country-code=\"CF\" >Central African Republic<\/option><option value=\"Chad\" data-country-code=\"TD\" >Chad<\/option><option value=\"Chile\" data-country-code=\"CL\" >Chile<\/option><option value=\"China\" data-country-code=\"CN\" >China<\/option><option value=\"Christmas Island\" data-country-code=\"CX\" >Christmas Island<\/option><option value=\"Cocos Islands\" data-country-code=\"CC\" >Cocos Islands<\/option><option value=\"Colombia\" data-country-code=\"CO\" >Colombia<\/option><option value=\"Comoros\" data-country-code=\"KM\" >Comoros<\/option><option value=\"Congo, Democratic Republic of the\" data-country-code=\"CD\" >Congo, Democratic Republic of the<\/option><option value=\"Congo, Republic of the\" data-country-code=\"CG\" >Congo, Republic of the<\/option><option value=\"Cook Islands\" data-country-code=\"CK\" >Cook Islands<\/option><option value=\"Costa Rica\" data-country-code=\"CR\" >Costa Rica<\/option><option value=\"Croatia\" data-country-code=\"HR\" >Croatia<\/option><option value=\"Cuba\" data-country-code=\"CU\" >Cuba<\/option><option value=\"Cura\u00e7ao\" data-country-code=\"CW\" >Cura\u00e7ao<\/option><option value=\"Cyprus\" data-country-code=\"CY\" >Cyprus<\/option><option value=\"Czechia\" data-country-code=\"CZ\" >Czechia<\/option><option value=\"C\u00f4te d&#039;Ivoire\" data-country-code=\"CI\" >C\u00f4te d&#039;Ivoire<\/option><option value=\"Denmark\" data-country-code=\"DK\" >Denmark<\/option><option value=\"Djibouti\" data-country-code=\"DJ\" >Djibouti<\/option><option value=\"Dominica\" data-country-code=\"DM\" >Dominica<\/option><option value=\"Dominican Republic\" data-country-code=\"DO\" >Dominican Republic<\/option><option value=\"Ecuador\" data-country-code=\"EC\" >Ecuador<\/option><option value=\"Egypt\" data-country-code=\"EG\" >Egypt<\/option><option value=\"El Salvador\" data-country-code=\"SV\" >El Salvador<\/option><option value=\"Equatorial Guinea\" data-country-code=\"GQ\" >Equatorial Guinea<\/option><option value=\"Eritrea\" data-country-code=\"ER\" >Eritrea<\/option><option value=\"Estonia\" data-country-code=\"EE\" >Estonia<\/option><option value=\"Eswatini\" data-country-code=\"SZ\" >Eswatini<\/option><option value=\"Ethiopia\" data-country-code=\"ET\" >Ethiopia<\/option><option value=\"Falkland Islands\" data-country-code=\"FK\" >Falkland Islands<\/option><option value=\"Faroe Islands\" data-country-code=\"FO\" >Faroe Islands<\/option><option value=\"Fiji\" data-country-code=\"FJ\" >Fiji<\/option><option value=\"Finland\" data-country-code=\"FI\" >Finland<\/option><option value=\"France\" data-country-code=\"FR\" >France<\/option><option value=\"French Guiana\" data-country-code=\"GF\" >French Guiana<\/option><option value=\"French Polynesia\" data-country-code=\"PF\" >French Polynesia<\/option><option value=\"French South Territories\" data-country-code=\"TF\" >French South Territories<\/option><option value=\"Gabon\" data-country-code=\"GA\" >Gabon<\/option><option value=\"Gambia\" data-country-code=\"GM\" >Gambia<\/option><option value=\"Georgia\" data-country-code=\"GE\" >Georgia<\/option><option value=\"Germany\" data-country-code=\"DE\" >Germany<\/option><option value=\"Ghana\" data-country-code=\"GH\" >Ghana<\/option><option value=\"Gibraltar\" data-country-code=\"GI\" >Gibraltar<\/option><option value=\"Greece\" data-country-code=\"GR\" >Greece<\/option><option value=\"Greenland\" data-country-code=\"GL\" >Greenland<\/option><option value=\"Grenada\" data-country-code=\"GD\" >Grenada<\/option><option value=\"Guadeloupe\" data-country-code=\"GP\" >Guadeloupe<\/option><option value=\"Guam\" data-country-code=\"GU\" >Guam<\/option><option value=\"Guatemala\" data-country-code=\"GT\" >Guatemala<\/option><option value=\"Guernsey\" data-country-code=\"GG\" >Guernsey<\/option><option value=\"Guinea\" data-country-code=\"GN\" >Guinea<\/option><option value=\"Guinea-Bissau\" data-country-code=\"GW\" >Guinea-Bissau<\/option><option value=\"Guyana\" data-country-code=\"GY\" >Guyana<\/option><option value=\"Haiti\" data-country-code=\"HT\" >Haiti<\/option><option value=\"Heard Island And Mcdonald Island\" data-country-code=\"HM\" >Heard Island And Mcdonald Island<\/option><option value=\"Honduras\" data-country-code=\"HN\" >Honduras<\/option><option value=\"Hong Kong SAR China\" data-country-code=\"HK\" >Hong Kong SAR China<\/option><option value=\"Hungary\" data-country-code=\"HU\" >Hungary<\/option><option value=\"Iceland\" data-country-code=\"IS\" >Iceland<\/option><option value=\"India\" data-country-code=\"IN\" >India<\/option><option value=\"Indonesia\" data-country-code=\"ID\" >Indonesia<\/option><option value=\"Iran\" data-country-code=\"IR\" >Iran<\/option><option value=\"Iraq\" data-country-code=\"IQ\" >Iraq<\/option><option value=\"Ireland\" data-country-code=\"IE\" >Ireland<\/option><option value=\"Isle of Man\" data-country-code=\"IM\" >Isle of Man<\/option><option value=\"Israel\" data-country-code=\"IL\" >Israel<\/option><option value=\"Italy\" data-country-code=\"IT\" >Italy<\/option><option value=\"Jamaica\" data-country-code=\"JM\" >Jamaica<\/option><option value=\"Japan\" data-country-code=\"JP\" >Japan<\/option><option value=\"Jersey\" data-country-code=\"JE\" >Jersey<\/option><option value=\"Jordan\" data-country-code=\"JO\" >Jordan<\/option><option value=\"Kazakhstan\" data-country-code=\"KZ\" >Kazakhstan<\/option><option value=\"Kenya\" data-country-code=\"KE\" >Kenya<\/option><option value=\"Kiribati\" data-country-code=\"KI\" >Kiribati<\/option><option value=\"Kosovo\" data-country-code=\"XK\" >Kosovo<\/option><option value=\"Kuwait\" data-country-code=\"KW\" >Kuwait<\/option><option value=\"Kyrgyzstan\" data-country-code=\"KG\" >Kyrgyzstan<\/option><option value=\"Lao People&#039;s Democratic Republic\" data-country-code=\"LA\" >Lao People&#039;s Democratic Republic<\/option><option value=\"Latvia\" data-country-code=\"LV\" >Latvia<\/option><option value=\"Lebanon\" data-country-code=\"LB\" selected=\"selected\">Lebanon<\/option><option value=\"Lesotho\" data-country-code=\"LS\" >Lesotho<\/option><option value=\"Liberia\" data-country-code=\"LR\" >Liberia<\/option><option value=\"Libya\" data-country-code=\"LY\" >Libya<\/option><option value=\"Liechtenstein\" data-country-code=\"LI\" >Liechtenstein<\/option><option value=\"Lithuania\" data-country-code=\"LT\" >Lithuania<\/option><option value=\"Luxembourg\" data-country-code=\"LU\" >Luxembourg<\/option><option value=\"Macao SAR China\" data-country-code=\"MO\" >Macao SAR China<\/option><option value=\"Madagascar\" data-country-code=\"MG\" >Madagascar<\/option><option value=\"Malawi\" data-country-code=\"MW\" >Malawi<\/option><option value=\"Malaysia\" data-country-code=\"MY\" >Malaysia<\/option><option value=\"Maldives\" data-country-code=\"MV\" >Maldives<\/option><option value=\"Mali\" data-country-code=\"ML\" >Mali<\/option><option value=\"Malta\" data-country-code=\"MT\" >Malta<\/option><option value=\"Marshall Islands\" data-country-code=\"MH\" >Marshall Islands<\/option><option value=\"Martinique\" data-country-code=\"MQ\" >Martinique<\/option><option value=\"Mauritania\" data-country-code=\"MR\" >Mauritania<\/option><option value=\"Mauritius\" data-country-code=\"MU\" >Mauritius<\/option><option value=\"Mayotte\" data-country-code=\"YT\" >Mayotte<\/option><option value=\"Mexico\" data-country-code=\"MX\" >Mexico<\/option><option value=\"Micronesia\" data-country-code=\"FM\" >Micronesia<\/option><option value=\"Moldova\" data-country-code=\"MD\" >Moldova<\/option><option value=\"Monaco\" data-country-code=\"MC\" >Monaco<\/option><option value=\"Mongolia\" data-country-code=\"MN\" >Mongolia<\/option><option value=\"Montenegro\" data-country-code=\"ME\" >Montenegro<\/option><option value=\"Montserrat\" data-country-code=\"MS\" >Montserrat<\/option><option value=\"Morocco\" data-country-code=\"MA\" >Morocco<\/option><option value=\"Mozambique\" data-country-code=\"MZ\" >Mozambique<\/option><option value=\"Myanmar\" data-country-code=\"MM\" >Myanmar<\/option><option value=\"Namibia\" data-country-code=\"NA\" >Namibia<\/option><option value=\"Nauru\" data-country-code=\"NR\" >Nauru<\/option><option value=\"Nepal\" data-country-code=\"NP\" >Nepal<\/option><option value=\"Netherlands\" data-country-code=\"NL\" >Netherlands<\/option><option value=\"New Caledonia\" data-country-code=\"NC\" >New Caledonia<\/option><option value=\"New Zealand\" data-country-code=\"NZ\" >New Zealand<\/option><option value=\"Nicaragua\" data-country-code=\"NI\" >Nicaragua<\/option><option value=\"Niger\" data-country-code=\"NE\" >Niger<\/option><option value=\"Nigeria\" data-country-code=\"NG\" >Nigeria<\/option><option value=\"Niue\" data-country-code=\"NU\" >Niue<\/option><option value=\"Norfolk Island\" data-country-code=\"NF\" >Norfolk Island<\/option><option value=\"North Korea\" data-country-code=\"KP\" >North Korea<\/option><option value=\"North Macedonia\" data-country-code=\"MK\" >North Macedonia<\/option><option value=\"Northern Mariana Islands\" data-country-code=\"MP\" >Northern Mariana Islands<\/option><option value=\"Norway\" data-country-code=\"NO\" >Norway<\/option><option value=\"Oman\" data-country-code=\"OM\" >Oman<\/option><option value=\"Pakistan\" data-country-code=\"PK\" >Pakistan<\/option><option value=\"Palau\" data-country-code=\"PW\" >Palau<\/option><option value=\"Palestinian Territories\" data-country-code=\"PS\" >Palestinian Territories<\/option><option value=\"Panama\" data-country-code=\"PA\" >Panama<\/option><option value=\"Papua New Guinea\" data-country-code=\"PG\" >Papua New Guinea<\/option><option value=\"Paraguay\" data-country-code=\"PY\" >Paraguay<\/option><option value=\"Peru\" data-country-code=\"PE\" >Peru<\/option><option value=\"Philippines\" data-country-code=\"PH\" >Philippines<\/option><option value=\"Pitcairn Islands\" data-country-code=\"PN\" >Pitcairn Islands<\/option><option value=\"Poland\" data-country-code=\"PL\" >Poland<\/option><option value=\"Portugal\" data-country-code=\"PT\" >Portugal<\/option><option value=\"Puerto Rico\" data-country-code=\"PR\" >Puerto Rico<\/option><option value=\"Qatar\" data-country-code=\"QA\" >Qatar<\/option><option value=\"Romania\" data-country-code=\"RO\" >Romania<\/option><option value=\"Russia\" data-country-code=\"RU\" >Russia<\/option><option value=\"Rwanda\" data-country-code=\"RW\" >Rwanda<\/option><option value=\"R\u00e9union\" data-country-code=\"RE\" >R\u00e9union<\/option><option value=\"Saint Helena\" data-country-code=\"SH\" >Saint Helena<\/option><option value=\"Saint Kitts and Nevis\" data-country-code=\"KN\" >Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\" data-country-code=\"LC\" >Saint Lucia<\/option><option value=\"Saint Vincent and the Grenadines\" data-country-code=\"VC\" >Saint Vincent and the Grenadines<\/option><option value=\"Samoa\" data-country-code=\"WS\" >Samoa<\/option><option value=\"San Marino\" data-country-code=\"SM\" >San Marino<\/option><option value=\"Saudi Arabia\" data-country-code=\"SA\" >Saudi Arabia<\/option><option value=\"Senegal\" data-country-code=\"SN\" >Senegal<\/option><option value=\"Serbia\" data-country-code=\"RS\" >Serbia<\/option><option value=\"Seychelles\" data-country-code=\"SC\" >Seychelles<\/option><option value=\"Sierra Leone\" data-country-code=\"SL\" >Sierra Leone<\/option><option value=\"Singapore\" data-country-code=\"SG\" >Singapore<\/option><option value=\"Sint Maarten\" data-country-code=\"SX\" >Sint Maarten<\/option><option value=\"Slovakia\" data-country-code=\"SK\" >Slovakia<\/option><option value=\"Slovenia\" data-country-code=\"SI\" >Slovenia<\/option><option value=\"Solomon Islands\" data-country-code=\"SB\" >Solomon Islands<\/option><option value=\"Somalia\" data-country-code=\"SO\" >Somalia<\/option><option value=\"South Africa\" data-country-code=\"ZA\" >South Africa<\/option><option value=\"South Georgia and South Sandwich\" data-country-code=\"GS\" >South Georgia and South Sandwich<\/option><option value=\"South Korea\" data-country-code=\"KR\" >South Korea<\/option><option value=\"South Sudan\" data-country-code=\"SS\" >South Sudan<\/option><option value=\"Spain\" data-country-code=\"ES\" >Spain<\/option><option value=\"Sri Lanka\" data-country-code=\"LK\" >Sri Lanka<\/option><option value=\"St. Barth\u00e9lemy\" data-country-code=\"BL\" >St. Barth\u00e9lemy<\/option><option value=\"St. Martin\" data-country-code=\"MF\" >St. Martin<\/option><option value=\"St. Pierre &amp; Miquelon\" data-country-code=\"PM\" >St. Pierre &amp; Miquelon<\/option><option value=\"Sudan\" data-country-code=\"SD\" >Sudan<\/option><option value=\"Suriname\" data-country-code=\"SR\" >Suriname<\/option><option value=\"Svalbard and Jan Mayen\" data-country-code=\"SJ\" >Svalbard and Jan Mayen<\/option><option value=\"Sweden\" data-country-code=\"SE\" >Sweden<\/option><option value=\"Switzerland\" data-country-code=\"CH\" >Switzerland<\/option><option value=\"Syria\" data-country-code=\"SY\" >Syria<\/option><option value=\"S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe\" data-country-code=\"ST\" >S\u00e3o Tom\u00e9 &amp; Pr\u00edncipe<\/option><option value=\"Taiwan\" data-country-code=\"TW\" >Taiwan<\/option><option value=\"Tajikistan\" data-country-code=\"TJ\" >Tajikistan<\/option><option value=\"Tanzania\" data-country-code=\"TZ\" >Tanzania<\/option><option value=\"Thailand\" data-country-code=\"TH\" >Thailand<\/option><option value=\"Timor-Leste\" data-country-code=\"TL\" >Timor-Leste<\/option><option value=\"Togo\" data-country-code=\"TG\" >Togo<\/option><option value=\"Tokelau\" data-country-code=\"TK\" >Tokelau<\/option><option value=\"Tonga\" data-country-code=\"TO\" >Tonga<\/option><option value=\"Trinidad &amp; Tobago\" data-country-code=\"TT\" >Trinidad &amp; Tobago<\/option><option value=\"Tunisia\" data-country-code=\"TN\" >Tunisia<\/option><option value=\"Turkey\" data-country-code=\"TR\" >Turkey<\/option><option value=\"Turkmenistan\" data-country-code=\"TM\" >Turkmenistan<\/option><option value=\"Turks &amp; Caicos Islands\" data-country-code=\"TC\" >Turks &amp; Caicos Islands<\/option><option value=\"Tuvalu\" data-country-code=\"TV\" >Tuvalu<\/option><option value=\"U.S. Virgin Islands\" data-country-code=\"VI\" >U.S. Virgin Islands<\/option><option value=\"US Minor Outlying Islands\" data-country-code=\"UM\" >US Minor Outlying Islands<\/option><option value=\"Uganda\" data-country-code=\"UG\" >Uganda<\/option><option value=\"Ukraine\" data-country-code=\"UA\" >Ukraine<\/option><option value=\"United Arab Emirates\" data-country-code=\"AE\" >United Arab Emirates<\/option><option value=\"United Kingdom\" data-country-code=\"GB\" >United Kingdom<\/option><option value=\"United States of America (USA)\" data-country-code=\"US\" >United States of America (USA)<\/option><option value=\"Uruguay\" data-country-code=\"UY\" >Uruguay<\/option><option value=\"Uzbekistan\" data-country-code=\"UZ\" >Uzbekistan<\/option><option value=\"Vanuatu\" data-country-code=\"VU\" >Vanuatu<\/option><option value=\"Vatican City\" data-country-code=\"VA\" >Vatican City<\/option><option value=\"Venezuela\" data-country-code=\"VE\" >Venezuela<\/option><option value=\"Vietnam\" data-country-code=\"VN\" >Vietnam<\/option><option value=\"Wallis And Futuna Islands\" data-country-code=\"WF\" >Wallis And Futuna Islands<\/option><option value=\"Western Sahara\" data-country-code=\"EH\" >Western Sahara<\/option><option value=\"Yemen\" data-country-code=\"YE\" >Yemen<\/option><option value=\"Zambia\" data-country-code=\"ZM\" >Zambia<\/option><option value=\"Zimbabwe\" data-country-code=\"ZW\" >Zimbabwe<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-1\" class=\"forminator-field-phone forminator-col forminator-col-12 \"><div class=\"forminator-field\"><input type=\"text\" name=\"phone-1\" value=\"\" placeholder=\"Phone number\" id=\"forminator-field-phone-1_6a97ea6fc864d\" class=\"forminator-input forminator-field--phone\" data-required=\"\" aria-required=\"false\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"text-1\" class=\"forminator-field-text forminator-col forminator-col-12 \"><div class=\"forminator-field\"><input type=\"text\" name=\"text-1\" value=\"\" placeholder=\"Brief bio - Tell us about yourself and your background\" id=\"forminator-field-text-1_6a97ea6fc864d\" class=\"forminator-input forminator-name--field\" data-required=\"1\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"select-1\" class=\"forminator-field-select forminator-col forminator-col-12 \"><div class=\"forminator-field\"><select  id=\"forminator-form-8446__field--select-1_6a97ea6fc864d\" class=\"forminator-select--field forminator-select2 forminator-select2-multiple\" data-required=\"1\" name=\"select-1\" data-default-value=\"\" data-placeholder=\"To which section would you like to submit this work?\" data-search=\"false\" data-search-placeholder=\"To which section would you like to submit this work?\" data-checkbox=\"false\" data-allow-clear=\"false\" aria-labelledby=\"forminator-form-8446__field--select-1_6a97ea6fc864d-label\"><option value=\"\"  >To which section would you like to submit this work?<\/option><option value=\"one\"  data-calculation=\"0\">Art<\/option><option value=\"two\"  data-calculation=\"0\">Culture &amp; Heritage<\/option><option value=\"ECONOMICS\"  data-calculation=\"0\">Economics<\/option><option value=\"Energy-&amp;-Infrastructure\"  data-calculation=\"0\">Energy &amp; Infrastructure<\/option><option value=\"Environment\"  data-calculation=\"0\">Environment<\/option><option value=\"Healthcare\"  data-calculation=\"0\">Healthcare<\/option><option value=\"Human-rights\"  data-calculation=\"0\">Human Rights<\/option><option value=\"Mental-Health\"  data-calculation=\"0\">Mental Health<\/option><option value=\"Politics\"  data-calculation=\"0\">Politics<\/option><option value=\"Technology-&amp;-Innovation\"  data-calculation=\"0\">Technology &amp; Innovation<\/option><option value=\"Tourism\"  data-calculation=\"0\">Tourism<\/option><option value=\"Unsure\"  data-calculation=\"0\">Unsure<\/option><\/select><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"select-2\" class=\"forminator-field-select forminator-col forminator-col-12 \"><div class=\"forminator-field\"><select  id=\"forminator-form-8446__field--select-2_6a97ea6fc864d\" class=\"forminator-select--field forminator-select2 forminator-select2-multiple\" data-required=\"1\" name=\"select-2\" data-default-value=\"\" data-placeholder=\"Submission&#039;s format\" data-search=\"false\" data-search-placeholder=\"Submission&#039;s format\" data-checkbox=\"false\" data-allow-clear=\"false\" aria-labelledby=\"forminator-form-8446__field--select-2_6a97ea6fc864d-label\"><option value=\"\"  >Submission&#039;s format<\/option><option value=\"one\"  data-calculation=\"0\">Column<\/option><option value=\"two\"  data-calculation=\"0\">Essay<\/option><option value=\"Op-ed---commentary\"  data-calculation=\"0\">Op-ed \/ commentary<\/option><option value=\"Interview\"  data-calculation=\"0\">Interview<\/option><option value=\"Research-study\"  data-calculation=\"0\">Research Study<\/option><option value=\"Investigative-Article\"  data-calculation=\"0\">Investigative Article<\/option><option value=\"Artwork\"  data-calculation=\"0\">Artwork<\/option><option value=\"Video\"  data-calculation=\"0\">Video<\/option><option value=\"Infographic\"  data-calculation=\"0\">Infographic<\/option><option value=\"Statistics\"  data-calculation=\"0\">Statistics \/ Survey finding<\/option><option value=\"Other\"  data-calculation=\"0\">Other<\/option><\/select><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"upload-1\" class=\"forminator-field-upload forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-upload-1_6a97ea6fc864d\" id=\"forminator-field-upload-1_6a97ea6fc864d-label\" class=\"forminator-label\">Upload brief abstract and\/or content outline <span class=\"forminator-required\">*<\/span><\/label><div class=\"forminator-multi-upload \" data-element=\"upload-1_6a97ea6fc864d\" aria-describedby=\"forminator-field-upload-1_6a97ea6fc864d-description\"><input type=\"file\" name=\"upload-1[]\" id=\"forminator-field-upload-1_6a97ea6fc864d\" class=\"forminator-input-file-required do-validate forminator-field-upload-1_6a97ea6fc864d-8446\" multiple=\"multiple\" data-method=\"ajax\" data-size=\"20971520\" data-size-message=\"Maximum file size allowed is 20 MB. \"><div class=\"forminator-multi-upload-message\" aria-hidden=\"true\"><span class=\"forminator-icon-upload\" aria-hidden=\"true\"><\/span><p>Drag and Drop (or) <a class=\"forminator-upload-file--forminator-field-upload-1_6a97ea6fc864d\" href=\"#\" onclick=\"return false;\">Choose Files<\/a><\/p><\/div><\/div><span id=\"forminator-field-upload-1_6a97ea6fc864d-description\" class=\"forminator-description\">Please upload writing documents in PDF format<\/span><ul class=\"forminator-uploaded-files upload-container-upload-1_6a97ea6fc864d\"><\/ul><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"upload-2\" class=\"forminator-field-upload forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-upload-2_6a97ea6fc864d\" id=\"forminator-field-upload-2_6a97ea6fc864d-label\" class=\"forminator-label\">Upload 1 - 3 previous similar work samples <span class=\"forminator-required\">*<\/span><\/label><div class=\"forminator-multi-upload \" data-element=\"upload-2_6a97ea6fc864d\"><input type=\"file\" name=\"upload-2[]\" id=\"forminator-field-upload-2_6a97ea6fc864d\" class=\"forminator-input-file-required do-validate forminator-field-upload-2_6a97ea6fc864d-8446\" multiple=\"multiple\" data-method=\"ajax\" data-limit=\"3\" data-limit-message=\"You can upload a maximum of 3 files.\" data-size=\"20971520\" data-size-message=\"Maximum file size allowed is 20 MB. \"><div class=\"forminator-multi-upload-message\" aria-hidden=\"true\"><span class=\"forminator-icon-upload\" aria-hidden=\"true\"><\/span><p>Drag and Drop (or) <a class=\"forminator-upload-file--forminator-field-upload-2_6a97ea6fc864d\" href=\"#\" onclick=\"return false;\">Choose Files<\/a><\/p><\/div><\/div><ul class=\"forminator-uploaded-files upload-container-upload-2_6a97ea6fc864d\"><\/ul><\/div><\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Send Message<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"09c3961f87\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ar\/wp-json\/wp\/v2\/pages\/13391\" \/><input type=\"hidden\" name=\"form_id\" value=\"8446\"><input type=\"hidden\" name=\"page_id\" value=\"13391\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/al-rawiya.com\/ar\/%d8%a7%d9%83%d8%aa%d8%a8%d9%88%d8%a7-%d9%85%d8%b9%d9%86%d8%a7\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"forminator-multifile-hidden\" class=\"forminator-multifile-hidden\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-98e0da2\" data-id=\"98e0da2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d05d467 elementor-widget elementor-widget-spacer\" data-id=\"d05d467\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c113353 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c113353\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-89f7fa1\" data-id=\"89f7fa1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-42c4558 elementor-widget elementor-widget-spacer\" data-id=\"42c4558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0627\u0643\u062a\u0628 \u0645\u0639\u0646\u0627 Thank you for considering Al Rawiya for the publication of your work. Before submitting a pitch to Al Rawiya, please browse our website. We recommend you read the About Us page and our previous issues so that you can familiarize yourself with our tone, our mission, and what we\u2019ve already published. This will [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","_wpcom_ai_launchpad_about_page":false,"_wpcom_ai_launchpad_gallery_page":false,"_wpcom_ai_launchpad_contact_page":false,"_wpcom_ai_launchpad_events_page":false,"_wpcom_ai_launchpad_video_page":false,"_wpcom_ai_launchpad_portfolio_piece":false,"footnotes":""},"class_list":["post-13391","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/pages\/13391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/comments?post=13391"}],"version-history":[{"count":5,"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/pages\/13391\/revisions"}],"predecessor-version":[{"id":13673,"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/pages\/13391\/revisions\/13673"}],"wp:attachment":[{"href":"https:\/\/al-rawiya.com\/ar\/wp-json\/wp\/v2\/media?parent=13391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}